{"id":438,"date":"2025-09-17T10:25:44","date_gmt":"2025-09-17T08:25:44","guid":{"rendered":"https:\/\/seubert-fruechte.de\/?post_type=product&#038;p=438"},"modified":"2025-09-17T10:26:06","modified_gmt":"2025-09-17T08:26:06","slug":"rettich-rot-bund","status":"publish","type":"product","link":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/","title":{"rendered":"Rettich rot Bund"},"content":{"rendered":"<p data-start=\"112\" data-end=\"290\">Unsere <strong data-start=\"172\" data-end=\"190\">roten Rettiche<\/strong> begeistern mit ihrer leuchtend roten Schale, dem knackigen Biss und der angenehm w\u00fcrzig-scharfen Note. Sie sind reich an Vitaminen, Mineralstoffen und Ballaststoffen und bringen nicht nur Geschmack, sondern auch optische Frische auf den Teller. Ob als Rohkost, in Salaten, aufgeschnitten als Snack oder dekorativ auf Buffets \u2013 rote Rettiche sind vielseitig einsetzbar und eine attraktive Erg\u00e4nzung f\u00fcr Gastronomie, Catering und den Einzelhandel.<\/p>\n<p data-start=\"136\" data-end=\"366\"><strong>Hinweis zur Menge:\u00a0<\/strong><\/p>\n<p data-start=\"136\" data-end=\"366\">Menge 1 entspricht einem Bund<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unsere roten Rettiche begeistern mit ihrer leuchtend roten Schale, dem knackigen Biss und der angenehm w\u00fcrzig-scharfen Note. Sie sind reich an Vitaminen, Mineralstoffen und Ballaststoffen und bringen nicht nur Geschmack, sondern auch optische Frische auf den Teller. Ob als Rohkost, in Salaten, aufgeschnitten als Snack oder dekorativ auf Buffets \u2013 rote Rettiche sind vielseitig einsetzbar [&hellip;]<\/p>\n","protected":false},"featured_media":437,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[18],"product_tag":[],"class_list":{"0":"post-438","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gemuese","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rettich rot Bund - Seubert Fr\u00fcchte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rettich rot Bund - Seubert Fr\u00fcchte\" \/>\n<meta property=\"og:description\" content=\"Unsere roten Rettiche begeistern mit ihrer leuchtend roten Schale, dem knackigen Biss und der angenehm w\u00fcrzig-scharfen Note. Sie sind reich an Vitaminen, Mineralstoffen und Ballaststoffen und bringen nicht nur Geschmack, sondern auch optische Frische auf den Teller. Ob als Rohkost, in Salaten, aufgeschnitten als Snack oder dekorativ auf Buffets \u2013 rote Rettiche sind vielseitig einsetzbar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/\" \/>\n<meta property=\"og:site_name\" content=\"Seubert Fr\u00fcchte\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-17T08:26:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Rettich-rot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/\",\"url\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/\",\"name\":\"Rettich rot Bund - Seubert Fr\u00fcchte\",\"isPartOf\":{\"@id\":\"https:\/\/seubert-fruechte.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Rettich-rot.jpg\",\"datePublished\":\"2025-09-17T08:25:44+00:00\",\"dateModified\":\"2025-09-17T08:26:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/#primaryimage\",\"url\":\"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Rettich-rot.jpg\",\"contentUrl\":\"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Rettich-rot.jpg\",\"width\":960,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/seubert-fruechte.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/seubert-fruechte.de\/index.php\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rettich rot Bund\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/seubert-fruechte.de\/#website\",\"url\":\"https:\/\/seubert-fruechte.de\/\",\"name\":\"Seubert Fr\u00fcchte\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/seubert-fruechte.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rettich rot Bund - Seubert Fr\u00fcchte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/","og_locale":"de_DE","og_type":"article","og_title":"Rettich rot Bund - Seubert Fr\u00fcchte","og_description":"Unsere roten Rettiche begeistern mit ihrer leuchtend roten Schale, dem knackigen Biss und der angenehm w\u00fcrzig-scharfen Note. Sie sind reich an Vitaminen, Mineralstoffen und Ballaststoffen und bringen nicht nur Geschmack, sondern auch optische Frische auf den Teller. Ob als Rohkost, in Salaten, aufgeschnitten als Snack oder dekorativ auf Buffets \u2013 rote Rettiche sind vielseitig einsetzbar [&hellip;]","og_url":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/","og_site_name":"Seubert Fr\u00fcchte","article_modified_time":"2025-09-17T08:26:06+00:00","og_image":[{"width":960,"height":1280,"url":"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Rettich-rot.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/","url":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/","name":"Rettich rot Bund - Seubert Fr\u00fcchte","isPartOf":{"@id":"https:\/\/seubert-fruechte.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/#primaryimage"},"image":{"@id":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/#primaryimage"},"thumbnailUrl":"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Rettich-rot.jpg","datePublished":"2025-09-17T08:25:44+00:00","dateModified":"2025-09-17T08:26:06+00:00","breadcrumb":{"@id":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/#primaryimage","url":"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Rettich-rot.jpg","contentUrl":"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Rettich-rot.jpg","width":960,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/rettich-rot-bund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/seubert-fruechte.de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/seubert-fruechte.de\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Rettich rot Bund"}]},{"@type":"WebSite","@id":"https:\/\/seubert-fruechte.de\/#website","url":"https:\/\/seubert-fruechte.de\/","name":"Seubert Fr\u00fcchte","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seubert-fruechte.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/product\/438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/comments?post=438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/media\/437"}],"wp:attachment":[{"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/media?parent=438"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/product_brand?post=438"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/product_cat?post=438"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/product_tag?post=438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}