{"id":314,"date":"2025-09-08T11:35:58","date_gmt":"2025-09-08T09:35:58","guid":{"rendered":"https:\/\/seubert-fruechte.de\/?post_type=product&#038;p=314"},"modified":"2025-09-08T11:35:59","modified_gmt":"2025-09-08T09:35:59","slug":"basilikum-schale","status":"publish","type":"product","link":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/","title":{"rendered":"Basilikum Schale"},"content":{"rendered":"<p data-start=\"170\" data-end=\"532\">Unser frischer <strong data-start=\"184\" data-end=\"197\">Basilikum<\/strong> begeistert mit seinen leuchtend gr\u00fcnen Bl\u00e4ttern und dem intensiven, leicht s\u00fc\u00dflich-w\u00fcrzigen Aroma. Er ist eines der bekanntesten Kr\u00e4uter der mediterranen K\u00fcche und verleiht Pasta, Pizza, Salaten und Saucen eine unverwechselbare Frische. Ob als Garnitur, Zutat oder Hauptaroma \u2013 Basilikum ist vielseitig einsetzbar und in Gastronomie, Catering und Einzelhandel unverzichtbar.<\/p>\n<p data-start=\"136\" data-end=\"366\"><strong>Verpackung:<\/strong>\u00a0100gr je Schale<\/p>\n<p data-start=\"136\" data-end=\"366\"><strong>Hinweis zur Menge:\u00a0<\/strong><\/p>\n<p data-start=\"136\" data-end=\"366\">Menge 1 entspricht eine Schale<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unser frischer Basilikum begeistert mit seinen leuchtend gr\u00fcnen Bl\u00e4ttern und dem intensiven, leicht s\u00fc\u00dflich-w\u00fcrzigen Aroma. Er ist eines der bekanntesten Kr\u00e4uter der mediterranen K\u00fcche und verleiht Pasta, Pizza, Salaten und Saucen eine unverwechselbare Frische. Ob als Garnitur, Zutat oder Hauptaroma \u2013 Basilikum ist vielseitig einsetzbar und in Gastronomie, Catering und Einzelhandel unverzichtbar. Verpackung:\u00a0100gr je Schale [&hellip;]<\/p>\n","protected":false},"featured_media":315,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[23],"product_tag":[],"class_list":{"0":"post-314","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kraeuter","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Basilikum Schale - Seubert Fr\u00fcchte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Basilikum Schale - Seubert Fr\u00fcchte\" \/>\n<meta property=\"og:description\" content=\"Unser frischer Basilikum begeistert mit seinen leuchtend gr\u00fcnen Bl\u00e4ttern und dem intensiven, leicht s\u00fc\u00dflich-w\u00fcrzigen Aroma. Er ist eines der bekanntesten Kr\u00e4uter der mediterranen K\u00fcche und verleiht Pasta, Pizza, Salaten und Saucen eine unverwechselbare Frische. Ob als Garnitur, Zutat oder Hauptaroma \u2013 Basilikum ist vielseitig einsetzbar und in Gastronomie, Catering und Einzelhandel unverzichtbar. Verpackung:\u00a0100gr je Schale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/\" \/>\n<meta property=\"og:site_name\" content=\"Seubert Fr\u00fcchte\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T09:35:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Basilikum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/\",\"url\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/\",\"name\":\"Basilikum Schale - Seubert Fr\u00fcchte\",\"isPartOf\":{\"@id\":\"https:\/\/seubert-fruechte.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Basilikum.jpg\",\"datePublished\":\"2025-09-08T09:35:58+00:00\",\"dateModified\":\"2025-09-08T09:35:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/#primaryimage\",\"url\":\"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Basilikum.jpg\",\"contentUrl\":\"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Basilikum.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/seubert-fruechte.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/seubert-fruechte.de\/index.php\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Basilikum Schale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/seubert-fruechte.de\/#website\",\"url\":\"https:\/\/seubert-fruechte.de\/\",\"name\":\"Seubert Fr\u00fcchte\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/seubert-fruechte.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Basilikum Schale - Seubert Fr\u00fcchte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/","og_locale":"de_DE","og_type":"article","og_title":"Basilikum Schale - Seubert Fr\u00fcchte","og_description":"Unser frischer Basilikum begeistert mit seinen leuchtend gr\u00fcnen Bl\u00e4ttern und dem intensiven, leicht s\u00fc\u00dflich-w\u00fcrzigen Aroma. Er ist eines der bekanntesten Kr\u00e4uter der mediterranen K\u00fcche und verleiht Pasta, Pizza, Salaten und Saucen eine unverwechselbare Frische. Ob als Garnitur, Zutat oder Hauptaroma \u2013 Basilikum ist vielseitig einsetzbar und in Gastronomie, Catering und Einzelhandel unverzichtbar. Verpackung:\u00a0100gr je Schale [&hellip;]","og_url":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/","og_site_name":"Seubert Fr\u00fcchte","article_modified_time":"2025-09-08T09:35:59+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Basilikum.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/","url":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/","name":"Basilikum Schale - Seubert Fr\u00fcchte","isPartOf":{"@id":"https:\/\/seubert-fruechte.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/#primaryimage"},"image":{"@id":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/#primaryimage"},"thumbnailUrl":"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Basilikum.jpg","datePublished":"2025-09-08T09:35:58+00:00","dateModified":"2025-09-08T09:35:59+00:00","breadcrumb":{"@id":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/#primaryimage","url":"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Basilikum.jpg","contentUrl":"https:\/\/seubert-fruechte.de\/wp-content\/uploads\/2025\/09\/Basilikum.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/seubert-fruechte.de\/index.php\/produkt\/basilikum-schale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/seubert-fruechte.de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/seubert-fruechte.de\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Basilikum Schale"}]},{"@type":"WebSite","@id":"https:\/\/seubert-fruechte.de\/#website","url":"https:\/\/seubert-fruechte.de\/","name":"Seubert Fr\u00fcchte","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seubert-fruechte.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/product\/314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/comments?post=314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/media\/315"}],"wp:attachment":[{"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/media?parent=314"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/product_brand?post=314"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/product_cat?post=314"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/seubert-fruechte.de\/index.php\/wp-json\/wp\/v2\/product_tag?post=314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}